{"id":271057,"date":"2024-08-02T14:16:36","date_gmt":"2024-08-02T12:16:36","guid":{"rendered":"https:\/\/global.global-tag.com\/applicazioni\/"},"modified":"2025-04-01T10:04:12","modified_gmt":"2025-04-01T08:04:12","slug":"applicazioni","status":"publish","type":"page","link":"https:\/\/www.global-tag.com\/it\/applicazioni\/","title":{"rendered":"Applicazioni"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(0,0,0,0.71)&#8221; custom_padding=&#8221;0%||0%||false|false&#8221; top_divider_style=&#8221;arrow&#8221; top_divider_color=&#8221;rgba(0,0,0,0.24)&#8221; top_divider_height=&#8221;122px&#8221; bottom_divider_color=&#8221;#E4254A&#8221; bottom_divider_height=&#8221;130px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;9f1baad1-7a02-4a00-97e0-ffbb41c307aa&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; custom_padding=&#8221;||3%||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Applicazioni RFID, NFC e Bluetooth Low Energy&#8221; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|800|||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;35px&#8221; background_enable_color=&#8221;off&#8221; custom_margin=&#8221;||0%||false|false&#8221; custom_padding=&#8221;0%||1%||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_heading title=&#8221;Una panoramica di dove i tag RFID e BLE di Global Tag vengono applicati&#8221; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h2&#8243; title_text_align=&#8221;center&#8221; background_enable_color=&#8221;off&#8221; custom_margin=&#8221;0%||1%||false|false&#8221; custom_padding=&#8221;3%||0%||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;rgba(255,255,255,0.68)&#8221; width=&#8221;80%&#8221; module_alignment=&#8221;center&#8221; min_height=&#8221;102.8px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;2%||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Per ogni tag di tuo interesse puoi trovare una pagina dedicata, in cui sono presenti le sue caratteristiche, la scheda tecnica specifica e le applicazioni RFID, NFC o BLE in cui il tag pu\u00f2 essere coinvolto. Compila il form che ti permette di contattarci o di personalizzare i transponder. Possiamo anche progettare e creare nuovi stampi per rendere i tag RFID, NFC o BLE una soluzione su misura per l&#8217;applicazione\/progetto RFID.<\/p>\n<p style=\"text-align: justify;\"><strong><\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; prev_background_color=&#8221;rgba(0,0,0,0.71)&#8221; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#ffffff 0%|rgba(0,0,0,0.05) 100%&#8221; background_enable_mask_style=&#8221;on&#8221; background_mask_style=&#8221;caret&#8221; background_mask_color=&#8221;#E4254A&#8221; background_mask_transform=&#8221;invert|rotate_90_degree|flip_vertical&#8221; background_mask_aspect_ratio=&#8221;portrait&#8221; background_mask_size=&#8221;cover&#8221; background_mask_position=&#8221;bottom_left&#8221; top_divider_style=&#8221;slant&#8221; top_divider_height=&#8221;51px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_de_mach_filter_posts filter_update_type=&#8221;update_field&#8221; reset_text=&#8221;Reset Filter&#8221; select2=&#8221;on&#8221; align_reset=&#8221;left&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|||on|||||&#8221; filter_headings_font=&#8221;|700||on|||||&#8221; background_color=&#8221;rgba(0,0,0,0.05)&#8221; custom_filter_params=&#8221;on&#8221; filter_params_text_size=&#8221;20px&#8221; filter_params_use_icon=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_de_mach_search_posts_item title=&#8221;Application Fields&#8221; acf_filter_type=&#8221;radio&#8221; taxonomy_order=&#8221;menu_order&#8221; exclude_option=&#8221;news, senza-categoria, applications-fields&#8221; custom_label=&#8221;Application fields&#8221; radio_show_empty=&#8221;on&#8221; hide_module_for_empty=&#8221;off&#8221; field_id=&#8221;Field_1_2_2&#8243; radio_select=&#8221;checkbox&#8221; filter_condition=&#8221;and&#8221; radio_style=&#8221;tick_box&#8221; hide_radio_all=&#8221;on&#8221; cat_tag_display_mode=&#8221;only_child&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; title_font_size=&#8221;13px&#8221; background_color=&#8221;#FFFFFF&#8221; background_enable_color=&#8221;on&#8221; custom_padding=&#8221;10px|10px|10px|10px|false|false&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_de_mach_search_posts_item][et_pb_de_mach_search_posts_item title=&#8221;Macrocategory&#8221; acf_filter_type=&#8221;radio&#8221; taxonomy_order=&#8221;menu_order&#8221; exclude_option=&#8221;news, senza-categoria, macrocategory&#8221; custom_label=&#8221;Macrocategory&#8221; radio_show_empty=&#8221;on&#8221; field_id=&#8221;Field_1_2_2_2&#8243; radio_select=&#8221;checkbox&#8221; filter_condition=&#8221;and&#8221; radio_style=&#8221;tick_box&#8221; hide_radio_all=&#8221;on&#8221; cat_tag_display_mode=&#8221;only_child&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; title_font_size=&#8221;13px&#8221; background_color=&#8221;#FFFFFF&#8221; background_enable_color=&#8221;on&#8221; custom_padding=&#8221;10px|10px|10px|10px|false|false&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_de_mach_search_posts_item][et_pb_de_mach_search_posts_item title=&#8221;Market Sector&#8221; acf_filter_type=&#8221;radio&#8221; taxonomy_order=&#8221;menu_order&#8221; exclude_option=&#8221;news, senza-categoria, market-sector&#8221; custom_label=&#8221;Market Sector&#8221; radio_show_empty=&#8221;on&#8221; field_id=&#8221;Field_1_2_2_2_2&#8243; radio_select=&#8221;checkbox&#8221; filter_condition=&#8221;and&#8221; radio_style=&#8221;tick_box&#8221; hide_radio_all=&#8221;on&#8221; cat_tag_display_mode=&#8221;only_child&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; title_font_size=&#8221;13px&#8221; background_color=&#8221;#FFFFFF&#8221; background_enable_color=&#8221;on&#8221; custom_padding=&#8221;10px|10px|10px|10px|false|false&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_de_mach_search_posts_item][\/et_pb_de_mach_filter_posts][et_pb_code _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<script><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->function hideElementsByXPath(xpath) {<!-- [et_pb_line_break_holder] -->  var elements = document.evaluate(xpath, document, null, XPathResult.UNORDERED_NODE_SNAPSHOT_TYPE, null);<!-- [et_pb_line_break_holder] -->  for (var i = 0; i < elements.snapshotLength; i++) {<!-- [et_pb_line_break_holder] -->    elements.snapshotItem(i).style.display = 'none';<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/\/ List of XPaths for elements to hide<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->var xpaths = [<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"165\"])[1]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"165\"])[2]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"165\"])[3]', \/\/<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"221\"])[1]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"221\"])[2]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"221\"])[3]', \/\/<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"268\"])[1]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"268\"])[2]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"268\"])[3]', \/\/<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"35\"])[1]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"35\"])[2]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"35\"])[3]', \/\/<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"2\"])[1]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"2\"])[2]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"2\"])[3]', \/\/<!-- [et_pb_line_break_holder] -->  \/\/\/\/\/ ******* filter 1 ******* \/\/\/\/\/<!-- [et_pb_line_break_holder] -->  \/\/ remove macrocategory from filter 1<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"221\"])[1]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"278\"])[1]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"277\"])[1]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"279\"])[1]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"280\"])[1]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"170\"])[1]',<!-- [et_pb_line_break_holder] -->  \/\/\/ remove market sectior from filter 1 \/\/\/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"268\"])[1]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"282\"])[1]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"284\"])[1]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"281\"])[1]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"283\"])[1]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"177\"])[1]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"316\"])[1]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"322\"])[1]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"304\"])[1]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"300\"])[1]',<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  \/\/\/\/ *** filter 2 ******* \/\/\/\/\/\/\/<!-- [et_pb_line_break_holder] -->  \/\/\/ remove application field sectior from filter 2 \/\/\/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"165\"])[2]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"276\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"269\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"273\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"270\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"271\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"272\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"321\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"274\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"275\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"308\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"312\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"169\"])[2]',<!-- [et_pb_line_break_holder] -->  \/\/\/ remove market sectior from filter 2 \/\/\/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"268\"])[2]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"282\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"284\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"281\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"283\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"177\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"316\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"322\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"304\"])[2]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"300\"])[2]',<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  \/\/\/\/**** filter 3 ******* \/\/\/\/\/\/<!-- [et_pb_line_break_holder] -->  \/\/ remove macrocategory from filter 3<!-- [et_pb_line_break_holder] -->  \/\/\/ remove application field sectior from filter 2 \/\/\/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"83\"])[3]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"276\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"269\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"273\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"270\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"271\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"272\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"321\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"274\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"275\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"308\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"312\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"169\"])[3]',<!-- [et_pb_line_break_holder] -->  \/\/'(\/\/*[@data_cat_id=\"87\"])[3]', \/\/<!-- [et_pb_line_break_holder] -->  \/\/\/\/\/ ******* filter 1 ******* \/\/\/\/\/<!-- [et_pb_line_break_holder] -->  \/\/ remove macrocategory from filter 1<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"221\"])[3]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"278\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"277\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"279\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"280\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"170\"])[3]',<!-- [et_pb_line_break_holder] -->    \/\/\/ remove market sectior from filter 3 \/\/\/\/<!-- [et_pb_line_break_holder] -->  \/*<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"267\"])[3]', \/\/<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"298\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"296\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"297\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"101\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"99\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"318\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"324\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"302\"])[3]',<!-- [et_pb_line_break_holder] -->  '(\/\/*[@data_cat_id=\"305\"])[3]',<!-- [et_pb_line_break_holder] -->  *\/<!-- [et_pb_line_break_holder] -->];<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/\/ Hide each element using its XPath<!-- [et_pb_line_break_holder] -->xpaths.forEach(function(xpath) {<!-- [et_pb_line_break_holder] -->  hideElementsByXPath(xpath);<!-- [et_pb_line_break_holder] -->});<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  <\/script>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_de_mach_archive_loop post_type_choose=&#8221;off|on|off|off|off|off|off|off&#8221; loop_layout=&#8221;261899&#8243; posts_number=&#8221;500&#8243; exclude_cats=&#8221;news, senza-categoria&#8221; equal_height=&#8221;on&#8221; align_last_bottom=&#8221;on&#8221; columns=&#8221;3&#8243; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; hover_transition_duration=&#8221;0ms&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_de_mach_archive_loop][et_pb_code _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<!-- Swiper JS --><!-- [et_pb_line_break_holder] -->  <script src=\"https:\/\/cdn.jsdelivr.net\/npm\/swiper@10\/swiper-bundle.min.js\"><\/script><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  <!-- Initialize Swiper --><!-- [et_pb_line_break_holder] -->  <script><!-- [et_pb_line_break_holder] -->    var swiper = new Swiper(\".mySwiper\", {<!-- [et_pb_line_break_holder] -->      navigation: {<!-- [et_pb_line_break_holder] -->        nextEl: \".swiper-button-next\",<!-- [et_pb_line_break_holder] -->        prevEl: \".swiper-button-prev\",<!-- [et_pb_line_break_holder] -->      },<!-- [et_pb_line_break_holder] -->    });<!-- [et_pb_line_break_holder] -->  <\/script>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<style><!-- [et_pb_line_break_holder] -->.bold-label {<!-- [et_pb_line_break_holder] -->            font-weight: bold;<!-- [et_pb_line_break_holder] -->        }<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->.bold-label-top {<!-- [et_pb_line_break_holder] -->            font-weight: bold;<!-- [et_pb_line_break_holder] -->        }<!-- [et_pb_line_break_holder] --><\/style>\n<p> <!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><script><!-- [et_pb_line_break_holder] -->        \/\/ Use XPath to locate the label by its ID<!-- [et_pb_line_break_holder] -->        const labelXPath = \"\/\/label[@data-value='applications-fields']\";<!-- [et_pb_line_break_holder] -->        const labelElement = document.evaluate(labelXPath, document, null, XPathResult.FIRST_ORDERED_NODE_TYPE, null).singleNodeValue;<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->        \/\/ Add a class to make the text bold<!-- [et_pb_line_break_holder] -->        if (labelElement) {<!-- [et_pb_line_break_holder] -->            labelElement.classList.add('bold-label');<!-- [et_pb_line_break_holder] -->        }<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->   \/\/ Use XPath to locate the label by its ID<!-- [et_pb_line_break_holder] -->        const labelXPath2 = \"\/\/label[@data-value='macrocategory']\";<!-- [et_pb_line_break_holder] -->        const labelElement2 = document.evaluate(labelXPath2, document, null, XPathResult.FIRST_ORDERED_NODE_TYPE, null).singleNodeValue;<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->        \/\/ Add a class to make the text bold<!-- [et_pb_line_break_holder] -->        if (labelElement2) {<!-- [et_pb_line_break_holder] -->            labelElement2.classList.add('bold-label-top');<!-- [et_pb_line_break_holder] -->        }<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->     \/\/ Use XPath to locate the label by its ID<!-- [et_pb_line_break_holder] -->        const labelXPath3 = \"\/\/label[@data-value='market-sector']\";<!-- [et_pb_line_break_holder] -->        const labelElement3 = document.evaluate(labelXPath3, document, null, XPathResult.FIRST_ORDERED_NODE_TYPE, null).singleNodeValue;<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->        \/\/ Add a class to make the text bold<!-- [et_pb_line_break_holder] -->        if (labelElement3) {<!-- [et_pb_line_break_holder] -->            labelElement3.classList.add('bold-label-top');<!-- [et_pb_line_break_holder] -->        }<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  \/\/ Use XPath to select all label elements<!-- [et_pb_line_break_holder] -->        const labelXPath4 = \"\/\/label\";<!-- [et_pb_line_break_holder] -->        const labelElements4 = document.evaluate(labelXPath4, document, null, XPathResult.ORDERED_NODE_SNAPSHOT_TYPE, null);<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->        \/\/ Loop through each label element and remove double hyphens from the text content<!-- [et_pb_line_break_holder] -->        for (let i = 0; i < labelElements4.snapshotLength; i++) {<!-- [et_pb_line_break_holder] -->            const labelElement4 = labelElements4.snapshotItem(i);<!-- [et_pb_line_break_holder] -->            labelElement4.textContent = labelElement4.textContent.replace(\/--\/g, '');<!-- [et_pb_line_break_holder] -->        }<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  \/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/<!-- [et_pb_line_break_holder] -->   \/\/ Use XPath to locate the label by its data_cat_id attribute<!-- [et_pb_line_break_holder] -->        const dataCatIdXPath = \"\/\/span[@data_cat_id='35']\";<!-- [et_pb_line_break_holder] -->        const labelElement5 = document.evaluate(dataCatIdXPath, document, null, XPathResult.FIRST_ORDERED_NODE_TYPE, null).singleNodeValue;<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->        \/\/ Add a class to make the text bold<!-- [et_pb_line_break_holder] -->        if (labelElement5) {<!-- [et_pb_line_break_holder] -->            labelElement5.style.paddingTop = \"20px\"; \/\/ Adjust the padding value as needed<!-- [et_pb_line_break_holder] -->        }<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->   \/\/ Use XPath to locate the label by its data_cat_id attribute<!-- [et_pb_line_break_holder] -->        const dataCatIdXPath2 = \"\/\/span[@data_cat_id='56']\";<!-- [et_pb_line_break_holder] -->        const labelElement6 = document.evaluate(dataCatIdXPath2, document, null, XPathResult.FIRST_ORDERED_NODE_TYPE, null).singleNodeValue;<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->        \/\/ Add a class to make the text bold<!-- [et_pb_line_break_holder] -->        if (labelElement6) {<!-- [et_pb_line_break_holder] -->            labelElement6.style.paddingTop = \"20px\"; \/\/ Adjust the padding value as needed<!-- [et_pb_line_break_holder] -->        }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->    <\/script><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><script><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->\/*<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  *\/<!-- [et_pb_line_break_holder] --><\/script><!-- [et_pb_line_break_holder] -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per ogni tag di tuo interesse puoi trovare una pagina dedicata, in cui sono presenti le sue caratteristiche, la scheda tecnica specifica e le applicazioni RFID, NFC o BLE in cui il tag pu\u00f2 essere coinvolto. Compila il form che ti permette di contattarci o di personalizzare i transponder. Possiamo anche progettare e creare nuovi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-271057","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Applicazioni - Global Tag<\/title>\n<meta name=\"description\" content=\"Una serie di applicazioni RFID, NFC e BLE per comprendere meglio dove come e perch\u00e8 utilizzare questa tecnologia nei propri progetti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.global-tag.com\/case-history\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Applicazioni\" \/>\n<meta property=\"og:description\" content=\"Una serie di applicazioni RFID, NFC e BLE per comprendere meglio dove come e perch\u00e8 utilizzare questa tecnologia nei propri progetti.\" \/>\n<meta property=\"og:site_name\" content=\"Global Tag\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T08:04:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Global_Tag_RFID\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.global-tag.com\\\/case-history\\\/\",\"url\":\"https:\\\/\\\/www.global-tag.com\\\/case-history\\\/\",\"name\":\"Applicazioni - Global Tag\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.global-tag.com\\\/#website\"},\"datePublished\":\"2024-08-02T12:16:36+00:00\",\"dateModified\":\"2025-04-01T08:04:12+00:00\",\"description\":\"Una serie di applicazioni RFID, NFC e BLE per comprendere meglio dove come e perch\u00e8 utilizzare questa tecnologia nei propri progetti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.global-tag.com\\\/case-history\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.global-tag.com\\\/case-history\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.global-tag.com\\\/case-history\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.global-tag.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Applicazioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.global-tag.com\\\/#website\",\"url\":\"https:\\\/\\\/www.global-tag.com\\\/\",\"name\":\"Global Tag\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.global-tag.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.global-tag.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.global-tag.com\\\/#organization\",\"name\":\"Global Tag\",\"url\":\"https:\\\/\\\/www.global-tag.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.global-tag.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.global-tag.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/GLOBAL-TAG-logo.ai_.png\",\"contentUrl\":\"https:\\\/\\\/www.global-tag.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/GLOBAL-TAG-logo.ai_.png\",\"width\":1771,\"height\":825,\"caption\":\"Global Tag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.global-tag.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Global_Tag_RFID\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/global-tag-srl---rfid-tag-for-global-request\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Applicazioni - Global Tag","description":"Una serie di applicazioni RFID, NFC e BLE per comprendere meglio dove come e perch\u00e8 utilizzare questa tecnologia nei propri progetti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.global-tag.com\/case-history\/","og_locale":"it_IT","og_type":"article","og_title":"Applicazioni","og_description":"Una serie di applicazioni RFID, NFC e BLE per comprendere meglio dove come e perch\u00e8 utilizzare questa tecnologia nei propri progetti.","og_site_name":"Global Tag","article_modified_time":"2025-04-01T08:04:12+00:00","twitter_card":"summary_large_image","twitter_site":"@Global_Tag_RFID","twitter_misc":{"Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.global-tag.com\/case-history\/","url":"https:\/\/www.global-tag.com\/case-history\/","name":"Applicazioni - Global Tag","isPartOf":{"@id":"https:\/\/www.global-tag.com\/#website"},"datePublished":"2024-08-02T12:16:36+00:00","dateModified":"2025-04-01T08:04:12+00:00","description":"Una serie di applicazioni RFID, NFC e BLE per comprendere meglio dove come e perch\u00e8 utilizzare questa tecnologia nei propri progetti.","breadcrumb":{"@id":"https:\/\/www.global-tag.com\/case-history\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.global-tag.com\/case-history\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.global-tag.com\/case-history\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.global-tag.com\/"},{"@type":"ListItem","position":2,"name":"Applicazioni"}]},{"@type":"WebSite","@id":"https:\/\/www.global-tag.com\/#website","url":"https:\/\/www.global-tag.com\/","name":"Global Tag","description":"","publisher":{"@id":"https:\/\/www.global-tag.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.global-tag.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.global-tag.com\/#organization","name":"Global Tag","url":"https:\/\/www.global-tag.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.global-tag.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.global-tag.com\/wp-content\/uploads\/2024\/11\/GLOBAL-TAG-logo.ai_.png","contentUrl":"https:\/\/www.global-tag.com\/wp-content\/uploads\/2024\/11\/GLOBAL-TAG-logo.ai_.png","width":1771,"height":825,"caption":"Global Tag"},"image":{"@id":"https:\/\/www.global-tag.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Global_Tag_RFID","https:\/\/www.linkedin.com\/company\/global-tag-srl---rfid-tag-for-global-request"]}]}},"_links":{"self":[{"href":"https:\/\/www.global-tag.com\/it\/wp-json\/wp\/v2\/pages\/271057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.global-tag.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.global-tag.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.global-tag.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.global-tag.com\/it\/wp-json\/wp\/v2\/comments?post=271057"}],"version-history":[{"count":22,"href":"https:\/\/www.global-tag.com\/it\/wp-json\/wp\/v2\/pages\/271057\/revisions"}],"predecessor-version":[{"id":278856,"href":"https:\/\/www.global-tag.com\/it\/wp-json\/wp\/v2\/pages\/271057\/revisions\/278856"}],"wp:attachment":[{"href":"https:\/\/www.global-tag.com\/it\/wp-json\/wp\/v2\/media?parent=271057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}